{"id":164922,"date":"2025-10-17T10:46:43","date_gmt":"2025-10-17T03:46:43","guid":{"rendered":"http:\/\/www.thestorythailand.com\/?p=164922"},"modified":"2026-09-01T19:47:49","modified_gmt":"2026-09-01T12:47:49","slug":"scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups","status":"publish","type":"post","link":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/","title":{"rendered":"SCB 10X joins AI2 Incubator&#8217;s $80M Fund III to launch 70 Applied AI startups"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e20\u0e32\u0e27\u0e30\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e38\u0e49\u0e19\u0e44\u0e17\u0e22\u0e0b\u0e1a\u0e40\u0e0b\u0e32\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e22\u0e32\u0e27\u0e19\u0e32\u0e19\u0e08\u0e19\u0e16\u0e39\u0e01\u0e02\u0e19\u0e32\u0e19\u0e19\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19 \u2018Lost Decade\u2019 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48\u0e2b\u0e32\u0e22\u0e44\u0e1b \u0e04\u0e33\u0e16\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e15\u0e48\u0e32\u0e07\u0e40\u0e1d\u0e49\u0e32\u0e04\u0e23\u0e38\u0e48\u0e19\u0e04\u0e34\u0e14 \u0e04\u0e37\u0e2d \u201c\u0e2b\u0e38\u0e49\u0e19\u0e44\u0e17\u0e22\u0e22\u0e31\u0e07\u0e19\u0e48\u0e32\u0e25\u0e07\u0e17\u0e38\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48?\u201d \u0e0b\u0e36\u0e48\u0e07 <strong>\u0e01\u0e27\u0e35 \u0e0a\u0e39\u0e01\u0e34\u0e08\u0e40\u0e01\u0e29\u0e21<\/strong> Value Investor \u0e0a\u0e37\u0e48\u0e2d\u0e14\u0e31\u0e07\u0e44\u0e14\u0e49\u0e43\u0e2b\u0e49\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e27\u0e49\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35 Money Freedom Forum 2025 \u0e27\u0e48\u0e32 \u0e41\u0e21\u0e49\u0e20\u0e32\u0e1e\u0e23\u0e27\u0e21\u0e08\u0e30\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e35\u0e48\u0e09\u0e38\u0e14\u0e23\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e15\u0e48\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e21\u0e37\u0e14\u0e21\u0e34\u0e14\u0e19\u0e31\u0e49\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e35\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48 \u0e1c\u0e48\u0e32\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 S-Curve \u0e25\u0e39\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e32\u0e01\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e21\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e21\u0e44\u0e1b<\/p>\n\n<h3 class=\"wp-block-heading\">\u0e20\u0e32\u0e1e\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19 13 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e2b\u0e32\u0e22\u0e44\u0e1b: Lost Decade \u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e38\u0e49\u0e19\u0e44\u0e17\u0e22<\/h3>\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e32\u0e01\u0e21\u0e2d\u0e07\u0e22\u0e49\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e15\u0e25\u0e2d\u0e14 13 \u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 (2013-2025) \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e20\u0e32\u0e1e\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e02\u0e2d\u0e07\u0e20\u0e32\u0e27\u0e30\u0e0a\u0e30\u0e07\u0e31\u0e01\u0e07\u0e31\u0e19\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e38\u0e49\u0e19\u0e44\u0e17\u0e22 \u0e14\u0e31\u0e0a\u0e19\u0e35\u0e41\u0e17\u0e1a\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e02\u0e22\u0e31\u0e1a\u0e44\u0e1b\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e40\u0e14\u0e34\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e01\u0e31\u0e1a\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e41\u0e1c\u0e48\u0e27\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e48\u0e32\u0e43\u0e08\u0e2b\u0e32\u0e22 \u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e40\u0e04\u0e22\u0e1e\u0e38\u0e48\u0e07\u0e17\u0e30\u0e22\u0e32\u0e19\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e1b\u0e35\u0e25\u0e30 7.7% \u0e43\u0e19\u0e22\u0e38\u0e04 S-Curve \u0e17\u0e35\u0e48 2 \u0e01\u0e47\u0e25\u0e14\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e25\u0e07\u0e21\u0e32\u0e40\u0e2b\u0e25\u0e37\u0e2d 4.6% \u0e43\u0e19\u0e22\u0e38\u0e04 S-Curve \u0e17\u0e35\u0e48 3 \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e14\u0e34\u0e48\u0e07\u0e25\u0e07\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e14\u0e31\u0e1a 2.2% \u0e43\u0e19\u0e17\u0e28\u0e27\u0e23\u0e23\u0e29\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e21\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e2b\u0e38\u0e49\u0e19\u0e44\u0e17\u0e22\u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e17\u0e33\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e22\u0e48\u0e33\u0e41\u0e22\u0e48\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e1b\u0e0f\u0e34\u0e40\u0e2a\u0e18\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e17\u0e35\u0e48\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e01\u0e27\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e15\u0e48\u0e23\u0e32\u0e01\u0e02\u0e2d\u0e07\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e14\u0e49\u0e2b\u0e22\u0e31\u0e48\u0e07\u0e25\u0e36\u0e01\u0e25\u0e07\u0e44\u0e1b\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e01\u0e27\u0e48\u0e32 \u0e27\u0e34\u0e01\u0e24\u0e15\u0e34\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e07\u0e2b\u0e32 S-Curve \u0e25\u0e39\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e44\u0e21\u0e48\u0e40\u0e08\u0e2d<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e27\u0e34\u0e01\u0e24\u0e15\u0e34\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e2a\u0e33\u0e04\u0e31\u0e0d 3 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e41\u0e23\u0e01\u0e04\u0e37\u0e2d \u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e2a\u0e39\u0e07\u0e27\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e33\u0e25\u0e31\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e16\u0e14\u0e16\u0e2d\u0e22 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e04\u0e37\u0e2d \u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e30 \u2018\u0e41\u0e01\u0e48\u0e01\u0e48\u0e2d\u0e19\u0e23\u0e27\u0e22\u2019 \u0e41\u0e25\u0e30\u0e17\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e04\u0e37\u0e2d \u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e2b\u0e19\u0e35\u0e49\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19 \u0e46 \u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01 \u0e41\u0e15\u0e48\u0e2a\u0e16\u0e32\u0e19\u0e30\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19 \u2018\u0e08\u0e19\u0e41\u0e25\u0e30\u0e21\u0e35\u0e2b\u0e19\u0e35\u0e49\u0e40\u0e22\u0e2d\u0e30\u2019 \u0e0b\u0e49\u0e33\u0e40\u0e15\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e48\u0e32\u0e19\u0e34\u0e22\u0e21 \u2018\u0e15\u0e34\u0e14\u0e2b\u0e23\u0e39\u2019 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e01\u0e23 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e44\u0e21\u0e48\u0e1b\u0e23\u0e32\u0e01\u0e0f \u0e04\u0e33\u0e16\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e36\u0e07\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e27\u0e48\u0e32 \u0e41\u0e25\u0e49\u0e27 S-Curve \u0e17\u0e35\u0e48 4 \u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e08\u0e30\u0e21\u0e32\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e43\u0e14?<\/p>\n\n<h3 class=\"wp-block-heading\">\u0e22\u0e49\u0e2d\u0e19\u0e23\u0e2d\u0e22 3 S-Curve: \u0e08\u0e32\u0e01 \u2018\u0e14\u0e34\u0e19\u2019 \u0e2a\u0e39\u0e48 \u2018\u0e01\u0e4a\u0e32\u0e0b\u2019 \u0e41\u0e25\u0e30 \u2018\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u2019<\/h3>\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15 \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d S-Curve \u0e41\u0e15\u0e48\u0e25\u0e30\u0e25\u0e39\u0e01\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e21\u0e32\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01 \u2018\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e25\u0e49\u0e33\u0e04\u0e48\u0e32\u2019 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27\u0e43\u0e2b\u0e49\u0e16\u0e39\u0e01\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e40\u0e27\u0e25\u0e32 \u0e43\u0e19 S-Curve \u0e41\u0e23\u0e01\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e19\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e0b\u0e36\u0e48\u0e07\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e22\u0e38\u0e04\u0e40\u0e01\u0e29\u0e15\u0e23\u0e01\u0e23\u0e23\u0e21\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e02\u0e49\u0e32\u0e27\u0e41\u0e25\u0e30\u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e48\u0e2d\u0e21\u0e32 S-Curve \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07 \u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e43\u0e15\u0e49\u0e1c\u0e37\u0e19\u0e14\u0e34\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 \u0e01\u0e4a\u0e32\u0e0b\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e0b\u0e36\u0e48\u0e07\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e22\u0e38\u0e04\u0e42\u0e0a\u0e15\u0e34\u0e0a\u0e48\u0e27\u0e07\u0e0a\u0e31\u0e0a\u0e27\u0e32\u0e25 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e32\u0e14\u0e17\u0e38\u0e19\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e49\u0e32\u0e27\u0e01\u0e23\u0e30\u0e42\u0e14\u0e14 \u0e41\u0e25\u0e30 S-Curve \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e41\u0e25\u0e30\u0e08\u0e31\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d \u0e17\u0e33\u0e40\u0e25\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e20\u0e39\u0e21\u0e34\u0e44\u0e14\u0e49\u0e1b\u0e25\u0e14\u0e25\u0e47\u0e2d\u0e01\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e49\u0e32\u0e1b\u0e25\u0e35\u0e01\u0e41\u0e25\u0e30\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e15\u0e2d\u0e01\u0e22\u0e49\u0e33\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e27\u0e48\u0e32 \u0e08\u0e38\u0e14\u0e41\u0e02\u0e47\u0e07\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e21\u0e35 \u2018\u0e02\u0e2d\u0e07\u0e14\u0e35\u2019 \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e42\u0e25\u0e01\u0e44\u0e14\u0e49\u0e40\u0e2a\u0e21\u0e2d<\/p>\n\n<h3 class=\"wp-block-heading\">S-Curve \u0e17\u0e35\u0e48 4 \u0e0b\u0e48\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 \u2018\u0e44\u0e1f\u0e1f\u0e49\u0e32-\u0e19\u0e49\u0e33-\u0e20\u0e39\u0e21\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u2019?: \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e22\u0e38\u0e04 AI \u0e41\u0e25\u0e30 EV<\/h3>\n\n<p class=\"wp-block-paragraph\">\u0e1a\u0e17\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e32\u0e01 3 S-Curve \u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15\u0e2d\u0e32\u0e08\u0e01\u0e33\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e43\u0e1a\u0e49\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e16\u0e36\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e42\u0e25\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e22\u0e38\u0e04 AI \u0e41\u0e25\u0e30\u0e22\u0e32\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e44\u0e1f\u0e1f\u0e49\u0e32 (EV) \u0e0b\u0e36\u0e48\u0e07\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e2d\u0e32\u0e08\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e2b\u0e21\u0e38\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e0b\u0e49\u0e33\u0e23\u0e2d\u0e22\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e37\u0e2d S-Curve \u0e17\u0e35\u0e48 4 \u0e2d\u0e32\u0e08\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e08\u0e32\u0e01\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e15\u0e48\u0e08\u0e30\u0e21\u0e32\u0e08\u0e32\u0e01 \u2018\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u2019 \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e38\u0e14\u0e21\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2d\u0e31\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e19\u0e49\u0e33 \u0e41\u0e25\u0e30\u0e20\u0e39\u0e21\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19\u0e04\u0e37\u0e2d Data Center \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e2d\u0e07\u0e02\u0e2d\u0e07 AI \u0e19\u0e31\u0e49\u0e19 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 \u2018\u0e44\u0e1f\u0e1f\u0e49\u0e32\u2019 \u0e41\u0e25\u0e30 \u2018\u0e19\u0e49\u0e33\u2019 \u0e43\u0e19\u0e1b\u0e23\u0e34\u0e21\u0e32\u0e13\u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e27\u0e25\u0e1c\u0e25\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e17\u0e31\u0e49\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e2a\u0e16\u0e35\u0e22\u0e23\u0e20\u0e32\u0e1e \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e2b\u0e21\u0e38\u0e19\u0e40\u0e27\u0e35\u0e22\u0e19\u0e08\u0e32\u0e01\u0e41\u0e2a\u0e07\u0e41\u0e14\u0e14\u0e17\u0e35\u0e48\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e23\u0e07\u0e40\u0e01\u0e37\u0e2d\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e21\u0e48\u0e40\u0e2b\u0e25\u0e47\u0e01\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e08\u0e32\u0e01\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e40\u0e14\u0e34\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e02\u0e49\u0e2d\u0e08\u0e33\u0e01\u0e31\u0e14\u0e14\u0e49\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e40\u0e23\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19 EV Hub \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08 \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e21\u0e35\u0e41\u0e23\u0e48\u0e2b\u0e32\u0e22\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e04\u0e37\u0e2d \u2018\u0e21\u0e34\u0e2a\u0e22\u0e39\u0e19\u0e34\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e2a\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e39\u0e21\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u2019 \u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48 \u0e13 \u0e08\u0e38\u0e14\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19\u0e41\u0e23\u0e48\u0e18\u0e32\u0e15\u0e38 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e21\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e44\u0e17\u0e22\u0e21\u0e35\u0e15\u0e49\u0e19\u0e17\u0e38\u0e19\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14<\/p>\n\n<h3 class=\"wp-block-heading\">\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e2b\u0e32\u0e22\u0e44\u0e1b: \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e25\u0e30\u2018\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e17\u0e22\u2019<\/h3>\n\n<p class=\"wp-block-paragraph\">\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e2b\u0e32 S-Curve \u0e25\u0e39\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e07\u0e21\u0e35 \u2018\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u2019 \u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e2a\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e2a\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e04\u0e49\u0e33\u0e08\u0e38\u0e19\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e0b\u0e36\u0e48\u0e07\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07\u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e2a\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e15\u0e49\u0e19\u0e41\u0e23\u0e01\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e41\u0e21\u0e49\u0e08\u0e30\u0e40\u0e04\u0e22\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e22\u0e31\u0e07\u0e04\u0e07\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e1b\u0e31\u0e01\u0e2b\u0e21\u0e38\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e15\u0e49\u0e19\u0e46 \u0e40\u0e2a\u0e21\u0e2d \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e08\u0e30\u0e1f\u0e37\u0e49\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e08\u0e38\u0e14\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e2a\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e04\u0e37\u0e2d <strong>Medical Tourism <\/strong>\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e01\u0e49\u0e32\u0e27\u0e02\u0e36\u0e49\u0e19\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e43\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48 3 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e17\u0e35\u0e21\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e48\u0e07\u0e01\u0e32\u0e08\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a \u0e1c\u0e19\u0e27\u0e01\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e14\u0e49\u0e32\u0e19\u0e28\u0e31\u0e25\u0e22\u0e01\u0e23\u0e23\u0e21\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e04\u0e23\u0e1a\u0e27\u0e07\u0e08\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e04\u0e37\u0e2d \u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e17\u0e22 \u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e15\u0e48\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e2b\u0e32\u0e28\u0e32\u0e25 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e2d\u0e31\u0e18\u0e22\u0e32\u0e28\u0e31\u0e22\u0e41\u0e25\u0e30\u0e21\u0e34\u0e15\u0e23\u0e44\u0e21\u0e15\u0e23\u0e35\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e35\u0e43\u0e04\u0e23\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e2d\u0e01\u0e40\u0e25\u0e35\u0e22\u0e19\u0e41\u0e1a\u0e1a\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e41\u0e15\u0e01\u0e15\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e41\u0e17\u0e49\u0e08\u0e23\u0e34\u0e07<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e1a\u0e17\u0e2a\u0e23\u0e38\u0e1b\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49 \u0e0a\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14\u0e2b\u0e38\u0e49\u0e19\u0e44\u0e17\u0e22\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e1b\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e34\u0e49\u0e19\u0e40\u0e0a\u0e34\u0e07 \u0e22\u0e38\u0e04\u0e17\u0e35\u0e48\u0e2b\u0e38\u0e49\u0e19\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e22\u0e01\u0e41\u0e1c\u0e07\u0e2d\u0e32\u0e08\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e20\u0e32\u0e1e\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15 \u0e41\u0e15\u0e48\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e44\u0e14\u0e49\u0e2b\u0e21\u0e14\u0e2a\u0e34\u0e49\u0e19\u0e44\u0e1b \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e01\u0e0e\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e19\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e31\u0e49\u0e07\u0e15\u0e25\u0e32\u0e14 \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e17\u0e35\u0e48 \u2018\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e15\u0e31\u0e27\u2019 (Stock Picking) \u0e42\u0e14\u0e22\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e0a\u0e19\u0e4c\u0e08\u0e32\u0e01 S-Curve \u0e25\u0e39\u0e01\u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e41\u0e25\u0e30 Data Center \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e25\u0e38\u0e48\u0e21\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e20\u0e39\u0e21\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e08\u0e33\u0e01\u0e31\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e04\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e04\u0e37\u0e2d\u0e19\u0e31\u0e01\u0e25\u0e07\u0e17\u0e38\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01 \u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07 \u0e44\u0e1b\u0e22\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e44\u0e14\u0e49\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32\u0e2a\u0e34\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e22\u0e48\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e1c\u0e25\u0e15\u0e2d\u0e1a\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1f\u0e49\u0e2d\u0e40\u0e2a\u0e21\u0e2d \u0e17\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e04\u0e33\u0e16\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 &#8220;\u0e08\u0e30\u0e25\u0e07\u0e17\u0e38\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e23\u0e48\u0e14\u0e35?&#8221; \u0e41\u0e15\u0e48\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e23\u0e30\u0e2b\u0e19\u0e31\u0e01\u0e27\u0e48\u0e32 &#8220;\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e04\u0e37\u0e2d\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e32\u0e19\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e23\u0e2d\u0e07\u0e25\u0e07\u0e21\u0e32\u0e04\u0e37\u0e2d\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49&#8221; \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e37\u0e2d\u0e01\u0e49\u0e32\u0e27\u0e41\u0e23\u0e01\u0e17\u0e35\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2a\u0e39\u0e48\u0e2d\u0e34\u0e2a\u0e23\u0e20\u0e32\u0e1e\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n\n<p class=\"wp-block-paragraph\">\u0e02\u0e48\u0e32\u0e27\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.thestorythailand.com\/15\/10\/2025\/164766\/\">MR. D.I.Y. \u0e1b\u0e31\u0e01\u0e18\u0e07 1,500 \u0e2a\u0e32\u0e02\u0e32 \u0e40\u0e1b\u0e34\u0e14\u0e09\u0e32\u0e01 IPO \u0e43\u0e2b\u0e0d\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e23\u0e2d\u0e1a 3 \u0e1b\u0e35<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.thestorythailand.com\/15\/10\/2025\/164613\/\">\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1f\u0e49\u0e2d\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e49\u0e19 Bitcoin \u0e04\u0e37\u0e2d\u0e17\u0e32\u0e07\u0e23\u0e2d\u0e14?<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.thestorythailand.com\/16\/10\/2025\/164808\/\">The Stock Master 2025: \u0e17\u0e33\u0e44\u0e21\u0e01\u0e32\u0e23 \u2018\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u2019 \u0e15\u0e25\u0e32\u0e14\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e27\u0e48\u0e32\u0e41\u0e04\u0e48 \u2018\u0e23\u0e39\u0e49\u2019 \u0e27\u0e34\u0e18\u0e35\u0e40\u0e17\u0e23\u0e14<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups. <\/p>\n","protected":false},"author":8,"featured_media":164920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121,13550],"tags":[19526,38274,38275,38276,38277,38278,4200,38279,6914,12667,14054],"class_list":["post-164922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-startup-en","category-13550","tag-applied-ai-2","tag-global-investment","tag-ai-house-seattle","tag-ai2-incubator-2","tag-fund-iii-2","tag-commercialization","tag-scb-10x-2","tag-pailin-pie-vichakul","tag-startup-2","tag-scbx-group","tag-venture-capital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCB 10X joins AI2 Incubator&#039;s $80M Fund III to launch 70 Applied AI startups - The Story Thailand<\/title>\n<meta name=\"description\" content=\"SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCB 10X joins AI2 Incubator&#039;s $80M Fund III to launch 70 Applied AI startups - The Story Thailand\" \/>\n<meta property=\"og:description\" content=\"SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/\" \/>\n<meta property=\"og:site_name\" content=\"The Story Thailand\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TheStoryThailand\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T03:46:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T12:47:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/10\/SCB-10X-AI2-Incubator-Fund-III.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"The Story Thailand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TheStoryThai\" \/>\n<meta name=\"twitter:site\" content=\"@TheStoryThai\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"The Story Thailand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/\"},\"author\":{\"name\":\"The Story Thailand\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#\\\/schema\\\/person\\\/c1e7741ac0d021bfe7dbfa16f537d399\"},\"headline\":\"SCB 10X joins AI2 Incubator&#8217;s $80M Fund III to launch 70 Applied AI startups\",\"datePublished\":\"2025-10-17T03:46:43+00:00\",\"dateModified\":\"2026-09-01T12:47:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/\"},\"wordCount\":65,\"publisher\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SCB-10X-AI2-Incubator-Fund-III.avif\",\"keywords\":[\"Applied AI\",\"Global Investment\",\"AI House Seattle\",\"AI2 Incubator\",\"Fund III\",\"Commercialization\",\"SCB 10X\",\"Pailin (Pie) Vichakul\",\"startup\",\"SCBX Group\",\"Venture Capital\"],\"articleSection\":[\"Startup\",\"\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\\\/\u0e01\u0e32\u0e23\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/\",\"name\":\"SCB 10X joins AI2 Incubator's $80M Fund III to launch 70 Applied AI startups - The Story Thailand\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SCB-10X-AI2-Incubator-Fund-III.avif\",\"datePublished\":\"2025-10-17T03:46:43+00:00\",\"dateModified\":\"2026-09-01T12:47:49+00:00\",\"description\":\"SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SCB-10X-AI2-Incubator-Fund-III.avif\",\"contentUrl\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/SCB-10X-AI2-Incubator-Fund-III.avif\",\"width\":1200,\"height\":622,\"caption\":\"SCB 10X \u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 Fund III \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 80 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e1b\u0e31\u0e49\u0e19 70 \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e15\u0e2d\u0e31\u0e1e Applied AI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SCB 10X joins AI2 Incubator&#8217;s $80M Fund III to launch 70 Applied AI startups\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/\",\"name\":\"The Story Thailand\",\"description\":\"Business and Digital Transformations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#organization\",\"name\":\"The Story Thailand\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/thestory_favicon-2.avif\",\"contentUrl\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/thestory_favicon-2.avif\",\"width\":512,\"height\":512,\"caption\":\"The Story Thailand\"},\"image\":{\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TheStoryThailand\\\/\",\"https:\\\/\\\/x.com\\\/TheStoryThai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/#\\\/schema\\\/person\\\/c1e7741ac0d021bfe7dbfa16f537d399\",\"name\":\"The Story Thailand\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-2-color-scaled-jpg-96x96.avif\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-2-color-scaled-jpg-96x96.avif\",\"contentUrl\":\"https:\\\/\\\/www.thestorythailand.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/logo-2-color-scaled-jpg-96x96.avif\",\"caption\":\"The Story Thailand\"},\"description\":\"\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e48\u0e32\u0e19 \u0e04\u0e31\u0e14\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \\\"\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49\\\" \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e49\u0e32\u0e27\u0e17\u0e31\u0e19\u0e42\u0e25\u0e01\u0e2d\u0e19\u0e32\u0e04\u0e15\",\"url\":\"https:\\\/\\\/www.thestorythailand.com\\\/en\\\/author\\\/thestoryth\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCB 10X joins AI2 Incubator's $80M Fund III to launch 70 Applied AI startups - The Story Thailand","description":"SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/","og_locale":"en_US","og_type":"article","og_title":"SCB 10X joins AI2 Incubator's $80M Fund III to launch 70 Applied AI startups - The Story Thailand","og_description":"SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups.","og_url":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/","og_site_name":"The Story Thailand","article_publisher":"https:\/\/www.facebook.com\/TheStoryThailand\/","article_published_time":"2025-10-17T03:46:43+00:00","article_modified_time":"2026-09-01T12:47:49+00:00","og_image":[{"width":1200,"height":622,"url":"http:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/10\/SCB-10X-AI2-Incubator-Fund-III.jpg","type":"image\/jpeg"}],"author":"The Story Thailand","twitter_card":"summary_large_image","twitter_creator":"@TheStoryThai","twitter_site":"@TheStoryThai","twitter_misc":{"Written by":"The Story Thailand","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#article","isPartOf":{"@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/"},"author":{"name":"The Story Thailand","@id":"https:\/\/www.thestorythailand.com\/en\/#\/schema\/person\/c1e7741ac0d021bfe7dbfa16f537d399"},"headline":"SCB 10X joins AI2 Incubator&#8217;s $80M Fund III to launch 70 Applied AI startups","datePublished":"2025-10-17T03:46:43+00:00","dateModified":"2026-09-01T12:47:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/"},"wordCount":65,"publisher":{"@id":"https:\/\/www.thestorythailand.com\/en\/#organization"},"image":{"@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/10\/SCB-10X-AI2-Incubator-Fund-III.avif","keywords":["Applied AI","Global Investment","AI House Seattle","AI2 Incubator","Fund III","Commercialization","SCB 10X","Pailin (Pie) Vichakul","startup","SCBX Group","Venture Capital"],"articleSection":["Startup","\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19\/\u0e01\u0e32\u0e23\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/","url":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/","name":"SCB 10X joins AI2 Incubator's $80M Fund III to launch 70 Applied AI startups - The Story Thailand","isPartOf":{"@id":"https:\/\/www.thestorythailand.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#primaryimage"},"image":{"@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#primaryimage"},"thumbnailUrl":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/10\/SCB-10X-AI2-Incubator-Fund-III.avif","datePublished":"2025-10-17T03:46:43+00:00","dateModified":"2026-09-01T12:47:49+00:00","description":"SCB 10X partners with AI2 Incubator through an $80M Fund III investment to launch 70 new Applied AI startups.","breadcrumb":{"@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#primaryimage","url":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/10\/SCB-10X-AI2-Incubator-Fund-III.avif","contentUrl":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/10\/SCB-10X-AI2-Incubator-Fund-III.avif","width":1200,"height":622,"caption":"SCB 10X \u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19 Fund III \u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 80 \u0e25\u0e49\u0e32\u0e19\u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d \u0e1b\u0e31\u0e49\u0e19 70 \u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e15\u0e2d\u0e31\u0e1e Applied AI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.thestorythailand.com\/en\/scb-10x-joins-ai2-incubators-80m-fund-iii-to-launch-70-applied-ai-startups\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.thestorythailand.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"SCB 10X joins AI2 Incubator&#8217;s $80M Fund III to launch 70 Applied AI startups"}]},{"@type":"WebSite","@id":"https:\/\/www.thestorythailand.com\/en\/#website","url":"https:\/\/www.thestorythailand.com\/en\/","name":"The Story Thailand","description":"Business and Digital Transformations","publisher":{"@id":"https:\/\/www.thestorythailand.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.thestorythailand.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.thestorythailand.com\/en\/#organization","name":"The Story Thailand","url":"https:\/\/www.thestorythailand.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thestorythailand.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/12\/thestory_favicon-2.avif","contentUrl":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2025\/12\/thestory_favicon-2.avif","width":512,"height":512,"caption":"The Story Thailand"},"image":{"@id":"https:\/\/www.thestorythailand.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TheStoryThailand\/","https:\/\/x.com\/TheStoryThai"]},{"@type":"Person","@id":"https:\/\/www.thestorythailand.com\/en\/#\/schema\/person\/c1e7741ac0d021bfe7dbfa16f537d399","name":"The Story Thailand","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2020\/07\/logo-2-color-scaled-jpg-96x96.avif","url":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2020\/07\/logo-2-color-scaled-jpg-96x96.avif","contentUrl":"https:\/\/www.thestorythailand.com\/wp-content\/uploads\/2020\/07\/logo-2-color-scaled-jpg-96x96.avif","caption":"The Story Thailand"},"description":"\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1c\u0e48\u0e32\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e41\u0e21\u0e48\u0e19\u0e22\u0e33\u0e41\u0e25\u0e30\u0e19\u0e48\u0e32\u0e2d\u0e48\u0e32\u0e19 \u0e04\u0e31\u0e14\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19 \"\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49\" \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e49\u0e32\u0e27\u0e17\u0e31\u0e19\u0e42\u0e25\u0e01\u0e2d\u0e19\u0e32\u0e04\u0e15","url":"https:\/\/www.thestorythailand.com\/en\/author\/thestoryth\/"}]}},"meta_box":{"open_icon":false,"close_icon":false,"open_text":false,"close_text":false,"layout":false,"effect":false,"name":false,"mobile":false,"tablet":false,"desktop":false,"mobile_gap":false,"tablet_gap":false,"desktop_gap":false,"alignment":false,"loop":false,"slides_to_scroll":false,"control":false,"delay":false,"direction":false,"speed":false,"arrow_svg":false,"display_arrows":false,"display_dots":false,"dots_location":false,"set_colors":false,"dot_color":false,"active_dot_color":false,"query_loop":false,"facebook_enable":false,"x_enable":false,"line_enable":false,"copy_link_enable":false,"embled_enable":false,"icon_color":false,"language":false,"limit":false,"show_excerpt":false,"show_date":false,"columns":false,"doc_id":false,"show_image":false,"show_meta":false},"_links":{"self":[{"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/posts\/164922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/comments?post=164922"}],"version-history":[{"count":1,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/posts\/164922\/revisions"}],"predecessor-version":[{"id":164923,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/posts\/164922\/revisions\/164923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/media\/164920"}],"wp:attachment":[{"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/media?parent=164922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/categories?post=164922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.thestorythailand.com\/en\/wp-json\/wp\/v2\/tags?post=164922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}